	<style type="text/css">
		.price, .cart, .shopping-cart, .woocommerce-variation-add-to-cart, .variations{
           display:none !important;
     	}
	</style>
{"id":33330,"date":"2016-06-30T08:32:20","date_gmt":"2016-06-30T08:32:20","guid":{"rendered":"https:\/\/abrasivosaguila.com\/product\/biantex-nettoyantblanchisseur-en-poudre-pour-sols-en-marbre-blanc\/"},"modified":"2017-08-29T07:03:09","modified_gmt":"2017-08-29T07:03:09","slug":"biantex-nettoyantblanchisseur-en-poudre-pour-sols-en-marbre-blanc","status":"publish","type":"product","link":"https:\/\/abrasivosaguila.com\/fr\/produit\/biantex-nettoyantblanchisseur-en-poudre-pour-sols-en-marbre-blanc\/","title":{"rendered":"BIANTEX   &#8211;   Nettoyant\/blanchisseur en poudre"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>BIANTEX nettoyant\/blanchisseur en poudre pour sols en marbre blanc est con\u00e7u pour \u00e9liminer tous r\u00e9sidus de salet\u00e9 incrust\u00e9e dans le marbre, il est sp\u00e9cialement efficace pour redonner une couleur blanche d\u00b4origine \u00e0 des marbres qui pr\u00e9sentent les typiques taches jaun\u00e2tres caus\u00e9es par le temps, l\u00b4oxydation et les entretiens inadapt\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Emploi<\/strong><\/p>\n<p>Ne pas diluer ou m\u00e9langer\u00a0 avec d\u2019autres produits.\u00a0 Verser une petite quantit\u00e9 du produit (20 g approximativement) sur une surface de 2 m2, ajoutant un peu d&rsquo;eau. Frotter avec une machine monobrosse \u00e9quip\u00e9e d\u2019un disque rouge o blanc, tout en cr\u00e9ant une p\u00e2te qui doit \u00eatre rependue\u00a0 sur la surface \u00e0 traiter. Rincer \u00e0 l&rsquo;eau claire et enlever tous les r\u00e9sidus.<\/p>\n","protected":false},"featured_media":30763,"template":"","meta":[],"product_brand":[],"product_cat":[1108,1112],"product_tag":[932,339,477,968],"class_list":{"0":"post-33330","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-poudres-et-pates-polissantes","7":"product_cat-nettoyeurs","8":"product_tag-blanchir","9":"product_tag-marbre","10":"product_tag-nettoyant","11":"product_tag-poudre","12":"description-off","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/abrasivosaguila.com\/fr\/wp-json\/wp\/v2\/product\/33330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abrasivosaguila.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/abrasivosaguila.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abrasivosaguila.com\/fr\/wp-json\/wp\/v2\/media\/30763"}],"wp:attachment":[{"href":"https:\/\/abrasivosaguila.com\/fr\/wp-json\/wp\/v2\/media?parent=33330"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/abrasivosaguila.com\/fr\/wp-json\/wp\/v2\/product_brand?post=33330"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/abrasivosaguila.com\/fr\/wp-json\/wp\/v2\/product_cat?post=33330"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/abrasivosaguila.com\/fr\/wp-json\/wp\/v2\/product_tag?post=33330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}